{"id":8845,"date":"2024-09-25T18:52:55","date_gmt":"2024-09-25T16:52:55","guid":{"rendered":"https:\/\/samantharadionline.com\/?p=8845"},"modified":"2024-09-25T18:52:56","modified_gmt":"2024-09-25T16:52:56","slug":"para-2027-rd-contara-con-un-excedente-de-generacion-energetica-superior-al-15","status":"publish","type":"post","link":"https:\/\/samantharadionline.com\/index.php\/2024\/09\/25\/para-2027-rd-contara-con-un-excedente-de-generacion-energetica-superior-al-15\/","title":{"rendered":"Para 2027, RD contar\u00e1 con un excedente de generaci\u00f3n energ\u00e9tica superior al 15%"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><em>En su discurso ante la ONU, Abinader indic\u00f3 que se ha iniciado la construcci\u00f3n de 2,000 nuevos megavatios (MW) de generaci\u00f3n t\u00e9rmica.<\/em><\/p>\n\n\n\n<p><img decoding=\"async\" width=\"60px\" height=\"60px\" src=\"https:\/\/listindiario.com\/files\/image_60_60\/uploads\/2023\/06\/26\/6499fb7b129ba.jpeg\" alt=\"Avatar del Carolina Pichardo\"><em>\u00a0<\/em>Carolina Pichardo,<strong> Santo Domingo, RD.<\/strong><\/p>\n\n\n\n<p>El presidente de la Rep\u00fablica, Luis Abinader, indic\u00f3 que&nbsp;<strong>para 2027 el pa\u00eds contar\u00e1 con un excedente de generaci\u00f3n energ\u00e9tica superior al 15%<\/strong>, lo que&nbsp;\u201cgarantizar\u00e1 una mayor estabilidad, sostenibilidad y mejores precios del suministro energ\u00e9tico\u201d.<\/p>\n\n\n\n<p>En su alocuci\u00f3n ante la 79\u00aa sesi\u00f3n de la Asamblea General de las Naciones Unidas, Abinader indic\u00f3 que se ha&nbsp;<strong>iniciado la construcci\u00f3n de 2,000 nuevos megavatios (MW)<\/strong>&nbsp;de generaci\u00f3n t\u00e9rmica de los cuales ya hay 400 instalados. Asimismo, agreg\u00f3 que han contratado&nbsp;1,674 MW de energ\u00eda renovable con 647 MW ya en operaci\u00f3n, y que 1,030 MW est\u00e1n en construcci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Por otro lado, el mandatario dominicano resalt\u00f3 que Am\u00e9rica Latina y El Caribe se encuentran en un<strong>&nbsp;momento crucial para la democracia<\/strong>; y que en los \u00faltimos a\u00f1os se ha percibido&nbsp;\u201cun preocupante deterioro en la calidad y el apoyo a los sistemas democr\u00e1ticos\u201d.<\/p>\n\n\n\n<p>Tambi\u00e9n agreg\u00f3 que este pa\u00eds deber\u00eda<strong>&nbsp;prestarle atenci\u00f3n a temas como la inseguridad o la crisis planetaria<\/strong>, sin embargo, debido al resurgimiento de la guerra y la violencia desbordada obliga a desviar la atenci\u00f3n a esta urgencia en la regi\u00f3n.&nbsp;<\/p>\n\n\n\n<p>\u201cExiste un consenso generalizado de que necesitamos con urgencia un nuevo modelo de gobernanza global. Uno que fomente mayor confianza y efectividad en las decisiones emanadas de este imprescindible concierto de naciones\u201d, admiti\u00f3.&nbsp;<\/p>\n\n\n\n<p>Dijo que para&nbsp;<strong>Rep\u00fablica Dominicana es prioridad tener un&nbsp;compromiso con un multilateralismo efectivo&nbsp;<\/strong>y renovado es prioritario, y que este es necesario para garantizar el respeto al derecho internacional y para proteger a las naciones frente a las amenazas globales que comprometen su seguridad y bienestar.&nbsp;<\/p>\n\n\n\n<p>\u201cDesde su formaci\u00f3n, Rep\u00fablica Dominicana ha sido&nbsp;<strong>un pueblo abanderado de la paz<\/strong>&nbsp;y de la&nbsp;<strong>soluci\u00f3n pac\u00edfica<\/strong>&nbsp;de los conflictos. La p\u00e9rdida de miles de vidas inocentes, ni\u00f1as, ni\u00f1os y envejecientes, resulta intolerable, por esto alzamos nuestra voz para reclamar de manera en\u00e9rgica la protecci\u00f3n efectiva de la poblaci\u00f3n civil conforme lo disponen las normas del derecho internacional humanitario\u201d, expres\u00f3 el presidente.<\/p>\n\n\n\n<p>El mandatario resalt\u00f3 que<strong>&nbsp;la democracia no puede reducirse a un sistema de procedimientos mec\u00e1nicos<\/strong>, sino a una realidad viva, que transforme a los ciudadanos.<\/p>\n\n\n\n<p>Abinader enumer\u00f3 que las&nbsp;<strong>c\u00edclicas crisis econ\u00f3micas globales<\/strong>&nbsp;que se han manifestado desde finales de la d\u00e9cada de los 1990, es una de lao principales factores de este declive.&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u201cOtro factor igualmente importante es que los ciudadanos no perciben los beneficios tangibles de la democracia, y muestran&nbsp;<strong>gran preocupaci\u00f3n por el personalismo y la corrupci\u00f3n,<\/strong>&nbsp;min\u00e1ndose la confianza en las instituciones democr\u00e1ticas\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p><em><strong>A continuaci\u00f3n el discurso \u00edntegro:&nbsp;<\/strong><\/em><\/p>\n\n\n\n<p><strong>PALABRAS PRESIDENTE LUIS ABINADER ASAMBLEA GENERAL DE LAS NACIONES UNIDAS<\/strong><\/p>\n\n\n\n<p>Excelent\u00edsimo Se\u00f1or Phil\u00e9mon Yang;<\/p>\n\n\n\n<p>Presidente de la 79ava. Asamblea General de las Naciones Unidas;<\/p>\n\n\n\n<p>Excelent\u00edsimo Se\u00f1or Ant\u00f3nio Guterres;<\/p>\n\n\n\n<p>Secretario General de las Naciones Unidas;<\/p>\n\n\n\n<p>Excelent\u00edsimos Se\u00f1ores Jefes de Estado y de Gobiernos;<\/p>\n\n\n\n<p>Honorables Jefes de delegaci\u00f3n:<\/p>\n\n\n\n<p>Se\u00f1oras y se\u00f1ores:<\/p>\n\n\n\n<p>Ante todo, deseo en nombre del pueblo dominicano felicitar la elecci\u00f3n del se\u00f1or Phil\u00e9mon Yang como presidente de esta Asamblea y a la vez agradecerle su trabajo, junto al Secretario General, por la exitosa organizaci\u00f3n de esta septuag\u00e9sima novena sesi\u00f3n y en particular de la reciente finalizada Cumbre del Futuro.<\/p>\n\n\n\n<p>Este ambicioso esfuerzo ha enfatizado la necesidad de fortalecer el financiamiento internacional para lograr el cumplimiento de los Objetivos de Desarrollo Sostenible (ODS), y muestra la voluntad sincera de trabajar por un presente y un futuro de paz, bienestar ciudadano y respeto a los derechos humanos y a los valores democr\u00e1ticos.<\/p>\n\n\n\n<p>Quiero resaltar que, en el caso de Rep\u00fablica Dominicana, hemos logrado avances considerables en los ODS en la reducci\u00f3n de la pobreza, la seguridad alimentaria, sostenibilidad energ\u00e9tica, seguridad ciudadana y acci\u00f3n clim\u00e1tica, por mencionar algunos ejemplos.<\/p>\n\n\n\n<p>A t\u00edtulo de ejemplo: la pobreza monetaria se redujo del 25.8% en 2019 al 23% en 2023, a pesar de la pandemia y los efectos de la guerra y en el primer semestre de este a\u00f1o, baj\u00f3 al 18.9 %, el nivel m\u00e1s bajo en nuestra historia.<\/p>\n\n\n\n<p>En estos cuatro a\u00f1os de gesti\u00f3n hemos m\u00e1s que duplicado el gasto destinado en la protecci\u00f3n social. Nuestra pol\u00edtica agr\u00edcola ha sido clave para garantizar la seguridad alimentaria y mantener la rentabilidad de los productores dominicanos. A pesar de ser una isla con recursos limitados de tierra cultivable, hemos pasado de un 88.5% de autosuficiencia alimentaria en 2019 a un 90.6% en 2023. Hemos logrado en gran medida la autosuficiencia en este sector.<\/p>\n\n\n\n<p>En cuanto a la generaci\u00f3n, transmisi\u00f3n y distribuci\u00f3n de energ\u00eda asequible y no contaminante, hemos alcanzado avances significativos, as\u00ed como importantes mejoras en las regulaciones el\u00e9ctricas. Iniciamos la construcci\u00f3n de 2,000 nuevos megavatios de generaci\u00f3n t\u00e9rmica de los cuales ya hay 400 MW instalados y contratamos 1,674 MW de energ\u00eda renovable con 647 MW ya en operaci\u00f3n y 1030 MW en construcci\u00f3n. Para finales de 2027, por primera vez, contaremos con un excedente de generaci\u00f3n superior al 15%, lo que garantizar\u00e1 una mayor estabilidad, y sostenibilidad y mejores precios del suministro energ\u00e9tico.<\/p>\n\n\n\n<p>La seguridad ciudadana tambi\u00e9n ha experimentado una mejora notable. En 2022, la tasa de homicidios en nuestro pa\u00eds fue de 13.2 por cada 100,000 habitantes; en 2023 descendi\u00f3 a 11.5, y en lo que va de 2024, se sit\u00faa en 9.9. Este \u00edndice est\u00e1 por debajo del promedio de Am\u00e9rica Latina y el Caribe, que seg\u00fan datos de la ONU es de 17.2.<\/p>\n\n\n\n<p>Mantenemos un firme compromiso de enfrentar la triple crisis planetaria (cambio clim\u00e1tico, p\u00e9rdida de biodiversidad y contaminaci\u00f3n) jugando un papel fundamental en la creaci\u00f3n del fondo para da\u00f1os y p\u00e9rdidas, y alcanzando la meta del 30&#215;30 en la protecci\u00f3n de nuestro territorio mar\u00edtimo.<\/p>\n\n\n\n<p>Estos cruciales temas requerir\u00edan toda nuestra atenci\u00f3n, sin embargo, el resurgimiento de la guerra y la violencia desbordada nos obligan a enfocar esta lamentable urgencia.<\/p>\n\n\n\n<p>Desde su aprobaci\u00f3n en 1945, la Carta de las Naciones Unidas nos ha servido bien, pero tras siete d\u00e9cadas se han acumulado una serie de retos y desaf\u00edos que hoy desbordan su marco institucional, como lo ha enfatizado el secretario general Guterres en su discurso de apertura. Existe un consenso generalizado de que necesitamos con urgencia un nuevo modelo de gobernanza global. Uno que fomente mayor confianza y efectividad en las decisiones emanadas de este imprescindible concierto de naciones.<\/p>\n\n\n\n<p>Para Rep\u00fablica Dominicana, el compromiso con un multilateralismo efectivo y renovado es prioritario. Este enfoque es necesario para garantizar el respeto al derecho internacional y para proteger a las naciones frente a las amenazas globales que comprometen su seguridad y bienestar. Sin una acci\u00f3n concertada y basada en principios, los cimientos de la comunidad internacional se seguir\u00e1n debilitando.<\/p>\n\n\n\n<p>Desde su formaci\u00f3n, Republica Dominicana ha sido un pueblo abanderado de la paz y de la soluci\u00f3n pac\u00edfica de los conflictos. La p\u00e9rdida de miles de vidas inocentes, ni\u00f1as, ni\u00f1os y envejecientes, resulta intolerable, por esto alzamos nuestra voz para reclamar de manera en\u00e9rgica la protecci\u00f3n efectiva de la poblaci\u00f3n civil conforme lo disponen las normas del derecho internacional humanitario.<\/p>\n\n\n\n<p>Una s\u00f3lida teor\u00eda postula que las democracias rara vez van a la guerra unas con otras. Los dominicanos estamos convencidos de que la promoci\u00f3n de la democracia es un elemento esencial para la construcci\u00f3n de una paz duradera.<\/p>\n\n\n\n<p>La democracia no puede reducirse a un sistema de procedimientos mec\u00e1nicos; la democracia tiene que ser una realidad viva, que transforme positivamente la vida de los ciudadanos.<\/p>\n\n\n\n<p>Se\u00f1or presidente,<\/p>\n\n\n\n<p>Nos encontramos en un momento crucial para la democracia en Am\u00e9rica Latina y el Caribe. En las \u00faltimas d\u00e9cadas, hemos sido testigos de un preocupante deterioro en la calidad y el apoyo a los sistemas democr\u00e1ticos. De acuerdo con la reconocida encuestadora Latinobar\u00f3metro, el apoyo a la democracia ha tenido una considerable disminuci\u00f3n entre el 2010 y el 2023, mientras que el apoyo al autoritarismo aument\u00f3 en el mismo per\u00edodo.<\/p>\n\n\n\n<p>M\u00faltiples factores inciden en este declive, entre ellos, las secuelas de las frecuentes crisis econ\u00f3micas globales que se han vuelto c\u00edclicas desde finales de los a\u00f1os 90. Pero otro factor igualmente importante es que los ciudadanos no perciben los beneficios tangibles de la democracia, y muestran gran preocupaci\u00f3n por el personalismo y la corrupci\u00f3n, min\u00e1ndose la confianza en las instituciones democr\u00e1ticas.<\/p>\n\n\n\n<p>Frente a ese panorama, resalta la propensi\u00f3n a perpetuarse en el poder, que en el caso de Am\u00e9rica Latina toma la forma de la reelecci\u00f3n indefinida; en los \u00faltimos 30 a\u00f1os esta tendencia ha ganado fuerza, erosionando la democracia. Tenemos el ejemplo de Venezuela, que combina la concentraci\u00f3n del poder, la persecuci\u00f3n de la oposici\u00f3n y la censura a los medios de comunicaci\u00f3n. Sin la debida transparencia que requiere cualquier proceso electoral y sin sustento documental alguno, la crisis no har\u00e1 m\u00e1s que agravarse.<\/p>\n\n\n\n<p>Seguiremos insistiendo en la publicaci\u00f3n de todas las actas electorales, su verificaci\u00f3n por instituciones imparciales y el respeto al resultado emanado de la voluntad del pueblo venezolano. Sin esta publicaci\u00f3n no puede declararse un ganador leg\u00edtimo.<\/p>\n\n\n\n<p>La alternancia en el poder es un elemento esencial para garantizar un ejercicio pol\u00edtico responsable y genuinamente participativo. La democracia parte de un principio fundacional: el perdedor tiene que aceptar su derrota y ejercer una oposici\u00f3n leal y constructiva. Otro principio democr\u00e1tico esencial establece que el ganador tiene el deber de no avasallar ni doblegar al adversario. La democracia no puede ser ejercida \u00fanicamente por y para los ganadores. La mayor\u00eda debe garantizar el respeto y la inclusi\u00f3n de las minor\u00edas que gozan de iguales derechos y deben ser tratados con equidad y justicia.<\/p>\n\n\n\n<p>Se\u00f1or presidente, el pasado 19 de mayo el pueblo dominicano me reeligi\u00f3 en la primera vuelta electoral para un segundo y \u00faltimo mandato presidencial, logrando, adem\u00e1s, una mayor\u00eda calificada en ambas c\u00e1maras del Congreso. Con la mirada puesta en el fortalecimiento de la democracia dominicana, present\u00e9, muy recientemente, una reforma constitucional ante el Congreso dominicano que busca consolidar el l\u00edmite a la reelecci\u00f3n presidencial de manera taxativa. Dos per\u00edodos consecutivos y nunca m\u00e1s.<\/p>\n\n\n\n<p>Esta reforma se propone dejar un legado de mayor estabilidad pol\u00edtica y social a las futuras generaciones y busca establecer un principio general de manera m\u00e1s clara y robusta: el poder es siempre transitorio y debe estar al servicio de la gente.<\/p>\n\n\n\n<p>Se\u00f1or presidente,<\/p>\n\n\n\n<p>Toda democracia exige un compromiso con la defensa de los derechos humanos; fundamental para proteger la dignidad y la libertad de cada individuo y brindar legitimidad al poder pol\u00edtico.<\/p>\n\n\n\n<p>El Gobierno dominicano est\u00e1 profundamente comprometido con la protecci\u00f3n de los derechos humanos a nivel nacional e internacional. Este compromiso forma parte integral de nuestra pol\u00edtica exterior, que establece la promoci\u00f3n y defensa de los derechos humanos como uno de sus principales pilares. Aqu\u00ed no hay c\u00e1lculos ni bandos, tan solo principios.<\/p>\n\n\n\n<p>Por eso, la crisis en Hait\u00ed merece una atenci\u00f3n especial. Desde hace m\u00e1s de tres a\u00f1os, la inestabilidad en el pa\u00eds vecino ha generado una presi\u00f3n significativa sobre nuestra seguridad. Venimos solicitando con firmeza el involucramiento de la comunidad internacional en un rol protag\u00f3nico y sostenido en la estabilizaci\u00f3n de Hait\u00ed. Esta es una necesidad estrat\u00e9gica para la seguridad en mi pa\u00eds y en toda la regi\u00f3n.<\/p>\n\n\n\n<p>El Estado dominicano ha asumido una alta responsabilidad ante la crisis haitiana que va mucho m\u00e1s all\u00e1 de lo que le corresponde, proporcionando servicios esenciales a una gran poblaci\u00f3n proveniente del pa\u00eds vecino.<\/p>\n\n\n\n<p>En 2023, las atenciones m\u00e9dicas a inmigrantes haitianos representaron el 12% del total de los servicios prestados a trav\u00e9s de nuestro sistema de salud p\u00fablica.<\/p>\n\n\n\n<p>Adem\u00e1s, actualmente hay cerca de 200 mil menores extranjeros en el sistema educativo p\u00fablico dominicano, de los cuales se estima que 147,906 son de origen haitiano.<\/p>\n\n\n\n<p>Estos datos reflejan la gran carga econ\u00f3mica y sentido humanitario de Rep\u00fablica Dominicana, pero solos, no podemos.<\/p>\n\n\n\n<p>Despu\u00e9s de un largo batallar por la aprobaci\u00f3n de varias resoluciones en el Consejo de Seguridad, finalmente se empez\u00f3 a vislumbrar un camino hacia la estabilidad con la creaci\u00f3n del Consejo Presidencial de Transici\u00f3n y la llegada de la Misi\u00f3n Multinacional de Apoyo a la Seguridad en Hait\u00ed.<\/p>\n\n\n\n<p>Aprovechamos la ocasi\u00f3n para agradecer a Kenia y al presidente Ruto, que ha cargado con la mayor parte de los efectivos que apoyan a la Polic\u00eda Nacional Haitiana, y a Estados Unidos, pa\u00eds que ha asumido la mayor carga financiera y log\u00edstica. Tambi\u00e9n a Jamaica, Bahamas y El Salvador que ya han enviado sus aportes. Asimismo, a CARICOM por sus esfuerzos en favor del di\u00e1logo y la concertaci\u00f3n en Hait\u00ed.<\/p>\n\n\n\n<p>Hasta ahora solo se han desplegado 400 efectivos de la MSS de un m\u00ednimo de dos mil requeridos para que la fuerza sea efectiva. Sin embargo, hoy d\u00eda no se han depositado en el fondo fiduciario para Hait\u00ed, los recursos requeridos para lograr el despliegue pleno de la fuerza y alcanzar los objetivos de pacificaci\u00f3n y respaldo a la eventual celebraci\u00f3n de elecciones libres, justas y transparentes.<\/p>\n\n\n\n<p>\u00a1Se\u00f1ores! hemos llegado a este punto con grandes sacrificios, pero a pr\u00e1cticamente un a\u00f1o de la celebraci\u00f3n de las elecciones en Hait\u00ed, a\u00fan no est\u00e1n dadas las condiciones para ello. No podemos permitir que los esfuerzos hasta aqu\u00ed alcanzados se desplomen, pues de lo contrario el colapso de Hait\u00ed ser\u00e1 inminente y sus consecuencias alcanzar\u00e1n a toda la regi\u00f3n. Esta misi\u00f3n significa una excepcional esperanza para el restablecimiento de la normalidad en Hait\u00ed. Un fracaso podr\u00eda implicar la necesidad de adoptar medidas dr\u00e1sticas para proteger nuestra seguridad nacional.<\/p>\n\n\n\n<p>Es inaceptable que a estas alturas algunos de los pa\u00edses que han tenido incidencia en la situaci\u00f3n haitiana o que se han comprometido con su soluci\u00f3n, no hayan cumplido plenamente con sus promesas. Mientras la seguridad nacional de mi pa\u00eds est\u00e9 implicada, no cesar\u00e9 de reclamar por la estabilidad de Hait\u00ed.<\/p>\n\n\n\n<p>Se\u00f1or presidente,<\/p>\n\n\n\n<p>Rep\u00fablica Dominicana y el gobierno que presido, seguir\u00e1n colaborando con la comunidad internacional de manera solidaria y comprometida para cumplir con los Objetivos de Desarrollo Sostenible.<\/p>\n\n\n\n<p>El panorama global nos exige actuar como una comunidad cohesionada, como un verdadero concierto de naciones, con una meta com\u00fan y una visi\u00f3n de futuro.<\/p>\n\n\n\n<p>Seremos evaluados por la historia, no solo por los discursos que pronunciemos en estos ilustres espacios, sino, de manera m\u00e1s importante, por las acciones que emprendamos en la pr\u00e1ctica.<\/p>\n\n\n\n<p>No podemos fallarle a nuestros pueblos.<\/p>\n\n\n\n<p>No podemos fallarle a la humanidad.<\/p>\n\n\n\n<p>No podemos fallarle al futuro.<\/p>\n\n\n\n<p>Muchas gracias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En su discurso ante la ONU, Abinader indic\u00f3 que se ha iniciado la construcci\u00f3n de<\/p>\n","protected":false},"author":1,"featured_media":8846,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-8845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/8845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/comments?post=8845"}],"version-history":[{"count":1,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/8845\/revisions"}],"predecessor-version":[{"id":8847,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/8845\/revisions\/8847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media\/8846"}],"wp:attachment":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media?parent=8845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/categories?post=8845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/tags?post=8845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}