{"id":5720,"date":"2024-06-10T13:32:28","date_gmt":"2024-06-10T11:32:28","guid":{"rendered":"https:\/\/samantharadionline.com\/?p=5720"},"modified":"2024-06-10T13:32:29","modified_gmt":"2024-06-10T11:32:29","slug":"trump-regresa-a-nevada-para-su-segundo-mitin-desde-que-fue-declarado-culpable","status":"publish","type":"post","link":"https:\/\/samantharadionline.com\/index.php\/2024\/06\/10\/trump-regresa-a-nevada-para-su-segundo-mitin-desde-que-fue-declarado-culpable\/","title":{"rendered":"Trump regresa a Nevada para su segundo mitin desde que fue declarado culpable"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><em>Trump contrat\u00f3 m\u00e9dicos adicionales, aument\u00f3 los ventiladores y permiti\u00f3 a sus seguidores ingresar con botellas de agua y sombrillas a un mitin al aire libre el domingo en Las Vegas, donde las temperaturas excedieron los<strong>\u00a037.8 grados Celsius<\/strong>\u00a0<\/em><\/p>\n\n\n\n<p>l expresidente&nbsp;<strong>Donald Trump&nbsp;<\/strong>se dirigi\u00f3 a los votantes bajo el calor abrasador de<strong>&nbsp;Las Vegas<\/strong>, dici\u00e9ndoles en alg\u00fan momento a sus partidarios que pidieran ayuda si la necesitaban y aparentemente molesto porque los teleprompters, seg\u00fan \u00e9l, no funcionaban.<\/p>\n\n\n\n<p>La campa\u00f1a del posible candidato republicano contrat\u00f3 m\u00e9dicos adicionales, aument\u00f3 los ventiladores y permiti\u00f3 a sus seguidores ingresar con botellas de agua y sombrillas a un mitin al aire libre el domingo en Las Vegas, donde las temperaturas excedieron los<strong>\u00a037.8 grados Celsius<\/strong>\u00a0(100 Fahrenheit).<a href=\"https:\/\/account.microsoft.com\/privacy\/ad-settings\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p>\u201cNo quiero que nadie se me vaya. Necesitamos a cada votante. Ustedes no me importan, s\u00f3lo quiero su voto\u201d, dijo y agreg\u00f3 que era broma.<\/p>\n\n\n\n<p>Antes de eso, se\u00f1al\u00f3 que el personal de campa\u00f1a brindar\u00eda ayuda a quienes se sintieran cansados y brome\u00f3 que \u201ctodos\u201d, incluso el Servicio Secreto de Estados Unidos, estaban preocupados por la seguridad de los reunidos, pero no por \u00e9l.<\/p>\n\n\n\n<p>\u201cNunca me mencionaron. Estoy ac\u00e1 arriba sudando como perro\u201d, coment\u00f3. \u201cEs un trabajo duro\u201d.<\/p>\n\n\n\n<p>Trump regres\u00f3 a Nevada, uno de los estados m\u00e1s disputados en las elecciones de noviembre, para su segundo mitin desde que fue declarado culpable de pagar para silenciar denuncias en su contra.<\/p>\n\n\n\n<p>La condena sin precedentes de un expresidente ha estimulado la recaudaci\u00f3n de fondos de Trump y galvanizado a sus partidarios, pero a\u00fan est\u00e1 por verse si influir\u00e1 en los votantes indecisos. Trump tiene programada el lunes una entrevista por videoconferencia con agentes de libertad condicional, un paso necesario antes de su sentencia de julio.Las temperaturas en el suroeste han bajado tras alcanzar m\u00e1ximos hist\u00f3ricos la semana pasada, pero se mantienen por encima de lo normal para esta \u00e9poca del a\u00f1o y superaron los\u00a0<strong>37.8 C (100 F)<\/strong>\u00a0en el mitin, que se llev\u00f3 a cabo en un parque con poca sombra al lado del aeropuerto.<\/p>\n\n\n\n<p>Avanzado en su discurso, Trump coment\u00f3 que \u201cno est\u00e1 tan mal\u201d como pens\u00f3 que estar\u00eda y agreg\u00f3 que estaba m\u00e1s molesto por el hecho de que los teleprompters no funcionaran bien, incluso cuando se burlaba del presidente&nbsp;<strong>Barack Obama<\/strong>&nbsp;por usarlos.<\/p>\n\n\n\n<p>\u201cPago un mont\u00f3n de dinero a la gente de los teleprompters y dir\u00eda que 20% del tiempo no funcionan\u201d, se\u00f1al\u00f3 y agreg\u00f3 que no le pagar\u00e1 al contratista que aport\u00f3 los teleprompters. \u201cEs un desastre\u201d.<\/p>\n\n\n\n<p>Los organizadores de la campa\u00f1a repartieron botellas de agua mientras los partidarios hac\u00edan fila para ser inspeccionados por agentes de seguridad. Dentro del lugar, hab\u00eda grandes ventiladores nebulizadores, paquetes grandes de agua y carpas de enfriamiento alrededor del per\u00edmetro. Las nubes se acercaron y se levant\u00f3 una brisa unas dos horas antes de la hora prevista para que Trump subiera al escenario, lo que ofreci\u00f3 una apariencia de alivio del sol opresivo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u201cEste es un calor seco. Esto no es nada para la gente de Las Vegas\u201d, dijo el presidente del Partido Republicano de Nevada, Michael McDonald. \u201cPero lo que simboliza para el resto de Estados Unidos, es que atravesaremos el infierno\u201d para elegir a Trump.<\/p>\n\n\n\n<p>McDonald y cinco republicanos m\u00e1s han sido acusados de presentar certificados al Congreso que falsamente declara a Trump el ganador de las elecciones presidenciales de<strong>&nbsp;noviembre de 2020&nbsp;<\/strong>y sus juicios fueron pospuestos para el pr\u00f3ximo a\u00f1o.<\/p>\n\n\n\n<p>Trump dijo que los agitadores que irrumpieron en el Capitolio el&nbsp;<strong>6 de enero de 2021<\/strong>&nbsp;eran \u201cv\u00edctimas\u201d de una \u201ctrampa\u201d.<\/p>\n\n\n\n<p>\u201cLo eran realmente, antes que otra cosa, son v\u00edctimas de lo que sucedi\u00f3. Lo \u00fanico que hac\u00edan era protestar por una elecci\u00f3n manipulada. Eso era lo que hac\u00edan. Y luego la polic\u00eda dijo: vayan adentro, vayan adentro, vayan adentro, vayan adentro\u201d, indic\u00f3. \u201cQu\u00e9 trampa fue aquella. Una cosa horrible, horrible\u201d.<\/p>\n\n\n\n<p>La teor\u00eda de conspiraci\u00f3n de que los agitadores del 6 de enero fueron motivados por los polic\u00edas est\u00e1 muy extendida, pero no tiene ninguna base expresa. Muchos de los que estaban en el Capitolio el 6 de enero han dicho \u2014orgullosa, p\u00fablica y reiteradamente\u2014 que lo hicieron para ayudar al entonces presidente.<\/p>\n\n\n\n<p>El mitin de Trump en Nevada, el tercero en el estado este a\u00f1o, se produce al final de una gira por el occidente que incluy\u00f3 varios eventos de recaudaci\u00f3n de fondos de los que se espera que reciba millones de d\u00f3lares.<\/p>\n\n\n\n<p>La dem\u00f3crata&nbsp;<strong>Hillary Clinton<\/strong>&nbsp;gan\u00f3<strong>&nbsp;Nevada en 2016<\/strong>, al igual que el presidente Joe Biden en 2020, pero fue el \u00fanico estado en disputa donde a Trump le fue mejor contra Biden que contra Clinton. En las elecciones intermedias de 2022, el gobernador de Nevada, Steve Sisolak, un dem\u00f3crata, fue el \u00fanico que no logr\u00f3 reelegirse.<\/p>\n\n\n\n<p>Trump espera que su fuerza entre los votantes de la clase trabajadora y el creciente inter\u00e9s de los hispanos lo lleven a la victoria en el estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trump contrat\u00f3 m\u00e9dicos adicionales, aument\u00f3 los ventiladores y permiti\u00f3 a sus seguidores ingresar con botellas<\/p>\n","protected":false},"author":1,"featured_media":5721,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundiales"],"_links":{"self":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/5720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/comments?post=5720"}],"version-history":[{"count":1,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/5720\/revisions"}],"predecessor-version":[{"id":5722,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/5720\/revisions\/5722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media\/5721"}],"wp:attachment":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media?parent=5720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/categories?post=5720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/tags?post=5720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}