{"id":28244,"date":"2026-07-15T12:35:10","date_gmt":"2026-07-15T16:35:10","guid":{"rendered":"https:\/\/samantharadionline.com\/?p=28244"},"modified":"2026-07-15T12:35:10","modified_gmt":"2026-07-15T16:35:10","slug":"se-durmieron-al-creer-que-la-vigencia-del-codigo-no-llegaba","status":"publish","type":"post","link":"https:\/\/samantharadionline.com\/index.php\/2026\/07\/15\/se-durmieron-al-creer-que-la-vigencia-del-codigo-no-llegaba\/","title":{"rendered":"Se durmieron al creer que la vigencia del C\u00f3digo no llegaba"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-medium-font-size\"><em>\u201cTodo el mundo se durmi\u00f3 porque creyeron que la fecha no llegaba\u201d, dijo Pacheco al hablar en el programa Hoy Mismo, en referencia a las modificaciones que se deb\u00edan hacer a la Ley 74-25 del C\u00f3digo Penal antes de su entrada en vigencia<\/em><\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/image_60_60\/uploads\/2023\/05\/24\/646e8604494e2.jpeg\" alt=\"Avatar del Yudelka Dom\u00ednguez\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00a0<\/em>Yudelka Dom\u00ednguez, Santo Domingo, RD.\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de la C\u00e1mara de Diputados, Alfredo Pacheco, expres\u00f3 que el pa\u00eds, en donde incluy\u00f3 a la Fundaci\u00f3n Institucionalidad y Justicia (Finjus), el Congreso Nacional y otros estamentos, \u201cse durmi\u00f3 un poquito en los laureles atendiendo otros tantos temas\u201d y no present\u00f3 las propuestas de modificaci\u00f3n al C\u00f3digo Penal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHay que reconocer que el pa\u00eds del cual es parte la Finjus, la&nbsp;<strong>Fundaci\u00f3n Institucionalidad y Justicia y, obviamente, el Congreso y todos los dem\u00e1s estamentos<\/strong>, se durmieron un poquito en los laureles atendiendo otros tantos temas que hay, con relaci\u00f3n a la entrada en vigor del C\u00f3digo Penal, que se le dio ese a\u00f1o de la denominada vacatio legis, que es como se denomina el periodo de receso de la entrada en vigor del mismo\u201d,&nbsp;dijo en referencia a las modificaciones que se deb\u00edan hacer a la Ley 74-25&nbsp; antes de su entrada en vigencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTodo el mundo se durmi\u00f3 porque creyeron que la fecha no llegaba\u201d, repiti\u00f3 Pacheco al hablar en el programa Hoy Mismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que en el Congreso Nacional estila trabajar hasta el 24 de julio, d\u00eda de la inauguraci\u00f3n de los Juegos Centroamericanos y del Caribe; \u201cpor lo tanto, tenemos&nbsp;<strong>que terminar temprano porque hay que ir a la inauguraci\u00f3n de los juegos<\/strong>\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se recuerda que la actual legislatura concluye el 26 de julio y, de acuerdo a Pacheco,&nbsp;<strong>el d\u00eda 29 rendir\u00e1n cuentas.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Argument\u00f3, adem\u00e1s, que las disquisiciones que existen referentes al&nbsp;<strong>C\u00f3digo Penal son en relaci\u00f3n a algunos \u201c8 o 9 art\u00edculos\u201d<\/strong>, adem\u00e1s de algunos errores materiales que \u201cse fueron\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La comisi\u00f3n tiene pautado reunirse nueva vez este mi\u00e9rcoles&nbsp;<strong>a las 12:00 del mediod\u00eda para continuar trabajando<\/strong>&nbsp;sobre todas las sugerencias que se han hecho y las que se hagan hasta ese mediod\u00eda, indic\u00f3.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLuego estimo yo, no puedo hablar por la comisi\u00f3n; continuar\u00e1 trabajando porque el Senado va a tener una sesi\u00f3n, la comisi\u00f3n entrar\u00e1 en receso y luego que el Senado termine, contin\u00faa trabajando con las propuestas que se reciban hasta hoy a las 6:00 de la tarde. Luego ma\u00f1ana tiene la comisi\u00f3n toda la ma\u00f1ana para cotejar las que se reciban entre hoy al mediod\u00eda y las 6:00 de la tarde y el tiempo material es perfectamente posible\u201d, expres\u00f3 Pacheco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que, a diferencia de lo que creen muchas personas,<strong>&nbsp;la entrada en vigencia del C\u00f3digo es el d\u00eda 5 de agosto en todo el pa\u00eds.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alfredo Pacheco expres\u00f3 que la procuradora Yeni Berenice Reynoso, Ricardo de los Santos, Antoliano Peralta, entre otras personalidades, han presentado propuestas de modificaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTiempo material hay de m\u00e1s\u201d, repiti\u00f3, al referirse a las horas para conocer las&nbsp;<strong>propuestas antes de ser aprobadas en la C\u00e1mara de Diputados el viernes.&nbsp;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cTodo el mundo se durmi\u00f3 porque creyeron que la fecha no llegaba\u201d, dijo Pacheco al<\/p>\n","protected":false},"author":1,"featured_media":28245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-28244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/28244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/comments?post=28244"}],"version-history":[{"count":1,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/28244\/revisions"}],"predecessor-version":[{"id":28246,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/28244\/revisions\/28246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media\/28245"}],"wp:attachment":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media?parent=28244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/categories?post=28244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/tags?post=28244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}