{"id":2806,"date":"2024-03-14T21:39:22","date_gmt":"2024-03-14T20:39:22","guid":{"rendered":"https:\/\/samantharadionline.com\/?p=2806"},"modified":"2024-03-14T21:39:23","modified_gmt":"2024-03-14T20:39:23","slug":"muere-el-nino-de-5-anos-del-fuego-que-se-produjo-en-el-carnaval-de-salcedo","status":"publish","type":"post","link":"https:\/\/samantharadionline.com\/index.php\/2024\/03\/14\/muere-el-nino-de-5-anos-del-fuego-que-se-produjo-en-el-carnaval-de-salcedo\/","title":{"rendered":"Muere el ni\u00f1o de 5 a\u00f1os del fuego que se produjo en el carnaval de Salcedo"},"content":{"rendered":"\n<p>Se trata de Adriel Leonardo, un menor de cinco a\u00f1os que qued\u00f3 con quemaduras de tercer grado tras el incendio en la cueva Los Toros, provocado por fuegos artificiales<\/p>\n\n\n\n<p><em>\u00a0<\/em>CARLA MORENO<\/p>\n\n\n\n<p><strong>Santo Domingo, RD<\/strong><\/p>\n\n\n\n<p>Falleci\u00f3 este jueves la&nbsp;<strong>primera v\u00edctima&nbsp;<\/strong>del&nbsp;<strong>fuego&nbsp;<\/strong>que afect\u00f3 el&nbsp;<strong>carnaval de Salcedo<\/strong>&nbsp;el pasado fin de semana.<\/p>\n\n\n\n<p>Se trata de&nbsp;<strong>Adriel Leonardo<\/strong>, un menor de cinco a\u00f1os que qued\u00f3 con quemaduras de tercer grado tras el incendio en la<strong>&nbsp;cueva Los Toros<\/strong>, provocado por&nbsp;<strong>fuegos artificiales<\/strong>.&nbsp;<\/p>\n\n\n\n<p><strong>Adriel&nbsp;<\/strong>era uno de los menores ingresados con quemaduras en hasta un 80% de sus cuerpos. Todos en estado cr\u00edtico.<\/p>\n\n\n\n<p>El infante muri\u00f3 en el<strong>&nbsp;Hospital Infantil Arturo Grull\u00f3n<\/strong>&nbsp;de Santiago, mientras recib\u00eda cuidados especiales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de Adriel Leonardo, un menor de cinco a\u00f1os que qued\u00f3 con quemaduras de<\/p>\n","protected":false},"author":1,"featured_media":2807,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-2806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/2806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/comments?post=2806"}],"version-history":[{"count":1,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/2806\/revisions"}],"predecessor-version":[{"id":2808,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/2806\/revisions\/2808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media\/2807"}],"wp:attachment":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media?parent=2806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/categories?post=2806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/tags?post=2806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}