{"id":2803,"date":"2024-03-14T21:36:34","date_gmt":"2024-03-14T20:36:34","guid":{"rendered":"https:\/\/samantharadionline.com\/?p=2803"},"modified":"2024-03-14T21:36:34","modified_gmt":"2024-03-14T20:36:34","slug":"presentaran-video-de-el-dotolcito-con-arma-en-las-manos","status":"publish","type":"post","link":"https:\/\/samantharadionline.com\/index.php\/2024\/03\/14\/presentaran-video-de-el-dotolcito-con-arma-en-las-manos\/","title":{"rendered":"Presentar\u00e1n video de El Dotolcito con arma en las manos"},"content":{"rendered":"\n<p>De acuerdo a las informaciones, El Dotolcito se observa en el audiovisual exhibiendo una pistola color negro, que de acuerdo a informaciones, se trata de la denominada peine 30<\/p>\n\n\n\n<p><strong>Santo Domingo, RD<\/strong><\/p>\n\n\n\n<p>El\u00a0<strong>Ministerio P\u00fablico<\/strong>\u00a0presentar\u00e1 como prueba contra los imputados de la muerte de\u00a0<strong>Joshua Omar Fern\u00e1ndez,\u00a0<\/strong>un video donde se observa\u00a0<strong>Wesley Vincent Carmona (El Dotolcito),\u00a0<\/strong>uno de los tres implicados, portando el arma de fuego que seg\u00fan el \u00f3rgano acusador, acab\u00f3 con la vida del joven estudiante de 19 a\u00f1os el 16 abril del 2023.<\/p>\n\n\n\n<p>De acuerdo a las informaciones,\u00a0<strong>El Dotolcito<\/strong>\u00a0se observa en el\u00a0<strong>audiovisual\u00a0<\/strong>exhibiendo una\u00a0<strong>pistola\u00a0<\/strong>color negro, que de acuerdo a informaciones, se trata de la denominada peine 30.<\/p>\n\n\n\n<p>El&nbsp;<strong>Ministerio P\u00fablico<\/strong>&nbsp;presenta como pruebas en la acusaci\u00f3n certificaciones alegadamente emitidas por el&nbsp;<strong>Ministerio de Interior y Polic\u00eda,&nbsp;<\/strong>donde acredita que&nbsp;<strong>El Dotolcito&nbsp;<\/strong>y los dem\u00e1s acusados no tienen permisos para porte y tenencia de armas de fuego.<\/p>\n\n\n\n<p>En la imputaci\u00f3n por la muerte de Joshua Omar Fern\u00e1ndez, tambi\u00e9n est\u00e1n&nbsp;<strong>Luis Brito Troncoso&nbsp;<\/strong>y&nbsp;<strong>Alison de Jes\u00fas P\u00e9rez Mej\u00eda&nbsp;<\/strong>(Chiquito).<\/p>\n\n\n\n<p>El jurista Jean Cristofer P\u00e9rez, abogado de la familia del occiso, reiter\u00f3 que esa arma podr\u00eda ser la homicida y que Joshua es la \u00fanica v\u00edctima de este crimen, \u201cpor lo que los culpables deben ser condenados ejemplarmente, con todo el peso de la ley\u201d.<\/p>\n\n\n\n<p>El pr\u00f3ximo viernes, el Segundo Tribunal Colegiado del Distrito Nacional continuar\u00e1 con el juicio en la fase de presentaci\u00f3n de pruebas testimoniales y periciales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acuerdo a las informaciones, El Dotolcito se observa en el audiovisual exhibiendo una pistola<\/p>\n","protected":false},"author":1,"featured_media":2804,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-2803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/2803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/comments?post=2803"}],"version-history":[{"count":1,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/2803\/revisions"}],"predecessor-version":[{"id":2805,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/2803\/revisions\/2805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media\/2804"}],"wp:attachment":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media?parent=2803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/categories?post=2803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/tags?post=2803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}