{"id":26359,"date":"2026-05-13T12:23:06","date_gmt":"2026-05-13T16:23:06","guid":{"rendered":"https:\/\/samantharadionline.com\/?p=26359"},"modified":"2026-05-13T12:23:07","modified_gmt":"2026-05-13T16:23:07","slug":"brandon-clarke-el-jugador-de-memphis-grizzlies-hallado-muerto-en-su-casa","status":"publish","type":"post","link":"https:\/\/samantharadionline.com\/index.php\/2026\/05\/13\/brandon-clarke-el-jugador-de-memphis-grizzlies-hallado-muerto-en-su-casa\/","title":{"rendered":"Brandon Clarke, el jugador de Memphis Grizzlies  hallado muerto en su casa"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><em>Clark naci\u00f3 en Vancouver, Canad\u00e1, y antes de llegar al baloncesto profesional tuvo un paso por el b\u00e1squet universitario. Su carrera comenz\u00f3 en 2015 con San Jos\u00e9 State y luego fue transferido a la Universidad de Gonzaga en 2017<\/em><\/p>\n\n\n\n<p><strong>LD, Santo Domingo, RD\u00a0<\/strong><\/p>\n\n\n\n<p id=\"m112362-112361-112363\"><strong>Brandon Clarke<\/strong>, un delantero de 29 a\u00f1os, falleci\u00f3 el pasado martes 12 de mayo, conforme comunic\u00f3 su agencia, Priority Sports y su equipo los&nbsp;<strong>Grizzlies de Memphis<\/strong>.<\/p>\n\n\n\n<p id=\"m112367-112366-112368\">Seg\u00fan una filial de NBC en Los \u00c1ngeles, Clarke fue hallado muerto el lunes en una vivienda del Valle de San Fernando, California, donde acudieron los param\u00e9dicos tras responder a una llamada de emergencia.<\/p>\n\n\n\n<p id=\"m112372-112371-112373\">La cadena afirm\u00f3 que las autoridades estaban investigando&nbsp;<strong>la muerte del deportista<\/strong>&nbsp;como una posible&nbsp;<strong>sobredosis de drogas<\/strong>. Las investigaciones de NBC fueron realizadas con fuentes policiales no identificadas.<\/p>\n\n\n\n<p id=\"m112377-112376-112378\">Clark naci\u00f3 en Vancouver, Canad\u00e1, y antes de llegar al baloncesto profesional tuvo un paso por el b\u00e1squet universitario. Su carrera comenz\u00f3 en 2015 con&nbsp;<strong>San Jos\u00e9 State<\/strong>&nbsp;y luego fue transferido a la Universidad de&nbsp;<strong>Gonzaga<\/strong>&nbsp;en 2017.<\/p>\n\n\n\n<p id=\"m112382-112381-112383\">El norteamericano no disput\u00f3 encuentros en la temporada 2017-18, pero volvi\u00f3 a estar en el tabloncillo la temporada siguiente y tuvo tiempo para ser uno de los m\u00e1s destacados de un quinteto que lleg\u00f3 hasta el&nbsp;<em>Elite 8<\/em>&nbsp;del&nbsp;<em>March Madness<\/em>&nbsp;de la NCAA en 2019.<\/p>\n\n\n\n<p id=\"m112387-112386-112388\">Al final, Clarke integr\u00f3 el All-American de la Regional Oeste junto a Jarret Culver, Matt Mooney, Rui Hachimura y Trent Forrest.<\/p>\n\n\n\n<p id=\"m112392-112391-112393\">Ese mismo calendario, fue seleccionado en la&nbsp;<strong>vig\u00e9sima primera ronda<\/strong>&nbsp;del Draft de la NBA por Oklahoma City Thunder; sin embargo, fue traspasado dos semanas despu\u00e9s a Memphis, donde jug\u00f3 durante siete a\u00f1os.<\/p>\n\n\n\n<p id=\"m112397-112396-112398\">En su primera temporada con la franquicia de la NBA, el canadiense promedi\u00f3 12.1 puntos, 5.9 rebotes y 1.4 asistencias, rendimiento que lo llev\u00f3 a unirse a su compa\u00f1ero de escuadra, Ja Morant, en el equipo&nbsp;<strong>All-Rookie de la NBA en 2020<\/strong>. En octubre de 2022 los Grizzlies le otorgaron una extensi\u00f3n de&nbsp;<strong>cuatro a\u00f1os y $52 millones<\/strong>.<\/p>\n\n\n\n<p id=\"m112402-112401-112403\">Conforme a la agencia de noticias internacionales AP, las lesiones lo limitaron a apenas disputar 72 de 246 partidos posibles en sus \u00faltimas tres temporadas.&nbsp;<\/p>\n\n\n\n<p id=\"m112407-112406-112408\">En su \u00faltima presencia en un calendario de la NBA (2025-26) solamente disput\u00f3 dos partidos por problemas de rodilla y pantorrilla y fuera de la duela fue protagonista de un arresto por conducir con exceso de velocidad y posesi\u00f3n de una sustancia controlada que, seg\u00fan se inform\u00f3, era kratom. El hecho ocurri\u00f3 el 1 de abril de 2026.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Clark naci\u00f3 en Vancouver, Canad\u00e1, y antes de llegar al baloncesto profesional tuvo un paso<\/p>\n","protected":false},"author":1,"featured_media":26360,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-26359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/26359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/comments?post=26359"}],"version-history":[{"count":1,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/26359\/revisions"}],"predecessor-version":[{"id":26361,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/26359\/revisions\/26361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media\/26360"}],"wp:attachment":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media?parent=26359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/categories?post=26359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/tags?post=26359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}