{"id":22973,"date":"2026-02-07T09:06:30","date_gmt":"2026-02-07T13:06:30","guid":{"rendered":"https:\/\/samantharadionline.com\/?p=22973"},"modified":"2026-02-07T09:06:31","modified_gmt":"2026-02-07T13:06:31","slug":"fp-y-pld-intensifican-ofensiva-por-liderazgo-de-la-oposicion","status":"publish","type":"post","link":"https:\/\/samantharadionline.com\/index.php\/2026\/02\/07\/fp-y-pld-intensifican-ofensiva-por-liderazgo-de-la-oposicion\/","title":{"rendered":"FP y PLD intensifican ofensiva por liderazgo de la oposici\u00f3n"},"content":{"rendered":"\n<p><strong>An\u00e1lisis pol\u00edtico, Manuel Figueroa<\/strong><\/p>\n\n\n\n<p id=\"m2503-2502-2504\">Los partidos Fuerza del Pueblo (FP) y de la Liberaci\u00f3n Dominicana (PLD) escenifican una intensa ofensiva por asumir el liderazgo de la oposici\u00f3n, un fen\u00f3meno que erosionar\u00eda eventuales alianzas para enfrentar con \u00e9xito al gobernante&nbsp;<strong>Partido Revolucionario Moderno (PRM)<\/strong>&nbsp;en las elecciones de 2028.<\/p>\n\n\n\n<p id=\"m2520-2519-2521\">Sus dos principales l\u00edderes pol\u00edticos, los expresidentes Leonel Fern\u00e1ndez y&nbsp;<strong>Danilo Medina<\/strong>, mantienen un radical antagonismo desde el Big Bang del PLD en 2019, que dej\u00f3 como resultado el surgimiento de Fuerza del Pueblo y el desprendimiento de catorce partidos aliados.<\/p>\n\n\n\n<p id=\"m2525-2524-2526\">Desde entonces el PLD, que hab\u00eda gobernado el pa\u00eds durante 20 a\u00f1os, 16 de ellos de manera consecutiva, y la&nbsp;<strong>Fuerza del Pueblo,<\/strong>&nbsp;se han desgarrado las vestiduras cayendo derrotados en las elecciones de 2020 y 2024, y facilitado un amplio triunfo en primera vuelta del PRM y su candidato presidencial&nbsp;<strong>Luis Abinader.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/68cec0faca35056d393170c473ad8d5a.safeframe.googlesyndication.com\/safeframe\/1-0-45\/html\/container.html\n<\/div><\/figure>\n\n\n\n<p id=\"m2530-2529-2531\">Las contradicciones entre&nbsp;<strong>Fern\u00e1ndez y Medina<\/strong>&nbsp;se energizaron otra vez al iniciar este a\u00f1o, tras la renuncia de decenas de dirigentes pelede\u00edstas encabezados por el exsenador Jos\u00e9 del Castillo, para inscribirse en<strong>&nbsp;Fuerza del Pueblo.<\/strong>&nbsp;Un trago amargo que apura el desamor de ambos l\u00edderes en los \u00faltimos siete a\u00f1os.<\/p>\n\n\n\n<p id=\"m2535-2534-2536\">En la dirigencia del partido de la bandera morada con la estrella amarilla prevalece la certeza de que siguen siendo la organizaci\u00f3n pol\u00edtica mejor estructurada del pa\u00eds. Esta motivaci\u00f3n llev\u00f3 a su&nbsp;<strong>presidente Medina<\/strong>&nbsp;a afirmar que no apoyar\u00e1n a nadie y quien quiera alianza tendr\u00eda que sumarse a ellos, en una evidente indirecta al partido verde.<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"m2540-2539-2541\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/composite_image\/uploads\/2026\/02\/06\/69867ac0159ff.jpeg\" alt=\"Danilo Medina, presidente del PLD.\"\/><figcaption class=\"wp-element-caption\">Danilo Medina, presidente del PLD.List\u00edn Diario<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">la trayectoria del pld<\/h3>\n\n\n\n<p id=\"m2552-2551-2553\">El PLD fue fundado en 1973 por el expresidente Juan Bosch, en medio los nefastos doce a\u00f1os del presidente&nbsp;<strong>Joaqu\u00edn Balaguer<\/strong>&nbsp;y las frustratorias cadenas de derrotas sufridas por su mentor, desde el golpe de Estado en 1963, la Guerra de Abril de 1965, su derrota electoral ante Balaguer en 1966 como candidato del&nbsp;<strong>Partido Revolucionario Dominicano (PRD)<\/strong>, y sus radicales contradicciones con dirigentes perrede\u00edstas.<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/68cec0faca35056d393170c473ad8d5a.safeframe.googlesyndication.com\/safeframe\/1-0-45\/html\/container.html\n<\/div><\/figure>\n\n\n\n<p id=\"m2557-2556-2558\">Desde 1978 al 1994 Bosch fue el candidato presidencial del PLD. No triunf\u00f3 en ninguna de las elecciones. O sea, en 1978 obtuvo un 1.1%, cuando el PRD y su candidato&nbsp;<strong>Antonio Guzm\u00e1n<\/strong>&nbsp;ganaron a&nbsp;<strong>Balaguer.<\/strong>&nbsp;En 1982 recibi\u00f3 el 9.8% de los votos, cuando el PRD volvi\u00f3 a ganar a Balaguer con su candidato&nbsp;<strong>Salvador Jorge Blanco.<\/strong><\/p>\n\n\n\n<p id=\"m2562-2561-2563\">Bosch y el PLD remontaron en 1986 al registrar el 17.9% de los votos, cuando Balaguer volvi\u00f3 al poder tras derrotar al PRD y su candidato<strong>&nbsp;Jacobo Majluta.<\/strong>&nbsp;El momento de mayor gloria del PLD la obtuvo en 1990, cuando Bosch obtuvo el 33.8% logrando un empate t\u00e9cnico con Balaguer, que finalmente retuvo el poder con los votos de los partidos aliados.<\/p>\n\n\n\n<p id=\"m2567-2566-2568\">La frustraci\u00f3n fue tan determinante en esta etapa hist\u00f3rica, que&nbsp;<strong>Bosch y el PLD&nbsp;<\/strong>volvieron a caer a un 13.1% de los votos en 1994, unos comicios que desataron grave crisis pol\u00edtica, cuando el&nbsp;<strong>PRD&nbsp;<\/strong>y su candidato&nbsp;<strong>Jos\u00e9 Francisco Pe\u00f1a G\u00f3mez<\/strong>&nbsp;alegaron un fraude colosal. Al final&nbsp;<strong>Balaguer<\/strong>&nbsp;retuvo el poder acortando el per\u00edodo a dos a\u00f1os y el Congreso prohibiendo la reelecci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/68cec0faca35056d393170c473ad8d5a.safeframe.googlesyndication.com\/safeframe\/1-0-45\/html\/container.html\n<\/div><\/figure>\n\n\n\n<p id=\"m2572-2571-2573\">El monto de gloria peledeista inici\u00f3 en 1996 cuando&nbsp;<strong>Leonel Fern\u00e1ndez<\/strong>&nbsp;triunfo por primera vez en las elecciones de ese a\u00f1o, impulsado en la segunda vuelta electoral por el&nbsp;<strong>Frente Patri\u00f3tico<\/strong>&nbsp;formado con el apoyo de presidente&nbsp;<strong>Balaguer<\/strong>, para vencer a&nbsp;<strong>Pe\u00f1a G\u00f3mez<\/strong>&nbsp;y el PRD, con el 51.2% de los sufragios.<\/p>\n\n\n\n<p id=\"m2577-2576-2578\">Este \u00e9xito se desvaneci\u00f3 en los comicios del 2000 cuando volvieron a probar el polvo de la derrota a manos de&nbsp;<strong>Hip\u00f3lito Mej\u00eda<\/strong>&nbsp;y el PRD, con Medina como su candidato presidencial que obtuvo un 24.3% en medio de la cr\u00edticas tras bastidores que apuntaban a la inercia del presidente Fern\u00e1ndez.<\/p>\n\n\n\n<p id=\"m2582-2581-2583\">Precisamente&nbsp;<strong>Fern\u00e1ndez&nbsp;<\/strong>recuper\u00f3 la presidencia en 2004 con un 57.1%, frustrando los intentos reeleccionista de<strong>&nbsp;Mej\u00eda.<\/strong>&nbsp;Pero la crisis en el PLD volvi\u00f3 a asomar su cabeza en el congreso elector de 2007, cuando Fern\u00e1ndez opt\u00f3 por la candidatura a la reelecci\u00f3n. Derrot\u00f3 a Medina y a su consigna \u00a1Ahora es\u2026ahora es! Al final el perdedor dej\u00f3 revoloteando la lapidaria frase: \u201cMe venci\u00f3 el Estado\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/68cec0faca35056d393170c473ad8d5a.safeframe.googlesyndication.com\/safeframe\/1-0-45\/html\/container.html\n<\/div><\/figure>\n\n\n\n<p id=\"m2587-2586-2588\">Tras la victoria electoral del tercer mandato del PLD se caldearon los \u00e1nimos a grado extremo, cuando los seguidores de Medina volvieron a advertir escaramuzas de seguidores de Fern\u00e1ndez para un nuevo intento reeleccionista en los comicios de 2012. Se desataron los demonios, pero la sangre no lleg\u00f3 al r\u00edo porque finalmente Medina gan\u00f3 la candidatura.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">el calvario de leonel&nbsp;<\/h3>\n\n\n\n<p id=\"m2592-2591-2593\">Despu\u00e9s del triunfo de Medina en las elecciones de 2012, derrotando a Hip\u00f3lito Mej\u00eda-PRD, con 51.2% y un apoyo descomunal del gobierno, inici\u00f3 el calvario de Fern\u00e1ndez en el PLD, que lo ha mantenido alejado de la Presidencia de la Rep\u00fablica en los \u00faltimos 14 a\u00f1os.<\/p>\n\n\n\n<p id=\"m2597-2596-2598\">Medina dimension\u00f3 el camino desde un principio. Cuando tom\u00f3 posesi\u00f3n el 16 de agosto de 2012 dej\u00f3 boquiabiertos a los leonelistas, que escucharon incr\u00e9dulos cuando el nuevo mandatario recurri\u00f3 a una f\u00e1bula para sugerir que lo que hab\u00eda encontrado en el gobierno era un malet\u00edn lleno de facturas por pagar.<\/p>\n\n\n\n<p id=\"m2602-2601-2603\">Los seguidores de Leonel volvieron a sufrir un trauma cuando en 2014 el comit\u00e9 pol\u00edtico aprob\u00f3 reformar la Constituci\u00f3n para posibilitar la reelecci\u00f3n de Medina, cuando abrigaban la idea de que su l\u00edder y presidente del partido volver\u00eda a agotar otro per\u00edodo. Luego todos los acuerdos fueron desconocidos por los danilistas.<\/p>\n\n\n\n<p id=\"m2607-2606-2608\">La reelecci\u00f3n se impuso y&nbsp;<strong>Medina<\/strong>&nbsp;gan\u00f3 con 61.74% al nuevo&nbsp;<strong>PRM<\/strong>&nbsp;de Abinader, 34.98%. Pero todo no concluye aqu\u00ed, los danilistas abrigaron la idea de una nueva reforma constitucional para seguir en 2020 y toda la oposici\u00f3n se lanz\u00f3 a las calles a protestar. Incluyendo Fern\u00e1ndez, a la saz\u00f3n presidente del&nbsp;<strong>PLD<\/strong>.<\/p>\n\n\n\n<p id=\"m2612-2611-2613\">Cuando finalmente fracasaron los aprestos reeleccionestas, el&nbsp;<strong>PLD&nbsp;<\/strong>convoc\u00f3 primarias internas con padr\u00f3n abierto en octubre de 2019, para elegir a su candidato presidencial. Entonces toda la atenci\u00f3n volvi\u00f3 a concentrarse en&nbsp;<strong>Fern\u00e1ndez<\/strong>&nbsp;como el triunfador indiscutible en esta contienda.<\/p>\n\n\n\n<p id=\"m2617-2616-2618\">No obstante, el presidente Medina sac\u00f3 debajo de la manga como precandidato al desconocido empresario&nbsp;<strong>Gonzalo Castillo<\/strong>. Los resultados fueron de espanto: Fern\u00e1ndez, 884,630 votos (47.29%); Gonzalo 911,923 votos (48.29%). Estos resultados decretaron la ruptura de Fern\u00e1ndez, que denunci\u00f3 fraude y decidi\u00f3 marcharse para fundar&nbsp;<strong>Fuerza del Pueblo,<\/strong>&nbsp;cuando ni la&nbsp;<strong>Junta Central Electoral<\/strong>&nbsp;le hizo caso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">una batalla desigual&nbsp;<\/h3>\n\n\n\n<p id=\"m2622-2621-2623\">Desde la divisi\u00f3n en 2019, el PLD y Fuerza del Pueblo han participado separados en las elecciones del 2020 y 2024, con unos resultados que dejan muy mal parada a la oposici\u00f3n dividida. Veamos: en 2020, en las elecciones celebradas el 5 de julio debido a la pandemia, el PLD con&nbsp;<strong>Gonzalo Castillo<\/strong>&nbsp;obtuvo 1,537,078, para una ca\u00edda a 37.46% con relaci\u00f3n al 2016. De estos votos 184,236 (4.48%) fueron aportados por ocho fuerzas pol\u00edticas aliadas en el denominado&nbsp;<strong>Bloque Progresista.<\/strong><\/p>\n\n\n\n<p id=\"m2627-2626-2628\">Mientras el nuevo partido fundado por Fern\u00e1ndez, se vio obligado a pactar con el&nbsp;<strong>Partido Refomista Social Cristiano (PRSC<\/strong>), que encabez\u00f3 la alianza junto a otras cuatro fuerzas pol\u00edticas minoritarias, que integraron la Gran Alianza Nacional Renovadora.&nbsp;<strong>Fuerza del Pueblo<\/strong>&nbsp;obtuvo un 8.90% de los votos, logrando as\u00ed situarse entre los partidos mayoritarios. Pero tanto el PLD como&nbsp;<strong>Fuerza del Pueblo&nbsp;<\/strong>cayeron derrotados en primera vuelta por el PRM y Abinader, que lograron un 52.52% junto a la alianza Unidos por el Cambio.<\/p>\n\n\n\n<p id=\"m2632-2631-2633\">En las elecciones del 2024 el PLD se sumergi\u00f3 en un abismo junto a su candidato presidencial&nbsp;<strong>Abel Mart\u00ednez,&nbsp;<\/strong>al obtener apenas 453,468 sufragio, un p\u00edrrico 10.8% sin lograr concertar ninguna alianza. En cambio&nbsp;<strong>Fuerza del Pueblo<\/strong>&nbsp;con&nbsp;<strong>Fern\u00e1ndez&nbsp;<\/strong>encabezando la alianza Juntos Podemos, ascendi\u00f3 al segundo lugar, con 1, 259, 427 votos (28.84%).<\/p>\n\n\n\n<p id=\"m2637-2636-2638\">Pero tambi\u00e9n en esa ocasi\u00f3n fueron superados ampliamente por el PRM y Abinader, co, 2,507,287 votos (57.45%), logrando concentrar la alianza Rep\u00fablica Dominicana Avanza, con m\u00e1s de 20 partidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>An\u00e1lisis pol\u00edtico, Manuel Figueroa Los partidos Fuerza del Pueblo (FP) y de la Liberaci\u00f3n Dominicana<\/p>\n","protected":false},"author":1,"featured_media":22974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-22973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion"],"_links":{"self":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/22973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/comments?post=22973"}],"version-history":[{"count":1,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/22973\/revisions"}],"predecessor-version":[{"id":22975,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/22973\/revisions\/22975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media\/22974"}],"wp:attachment":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media?parent=22973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/categories?post=22973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/tags?post=22973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}