{"id":21052,"date":"2025-11-11T15:15:07","date_gmt":"2025-11-11T19:15:07","guid":{"rendered":"https:\/\/samantharadionline.com\/?p=21052"},"modified":"2025-11-11T17:49:46","modified_gmt":"2025-11-11T21:49:46","slug":"apagon-nacional-blackoff-se-registra-en-subestacion-de-san-pedro-de-macoris","status":"publish","type":"post","link":"https:\/\/samantharadionline.com\/index.php\/2025\/11\/11\/apagon-nacional-blackoff-se-registra-en-subestacion-de-san-pedro-de-macoris\/","title":{"rendered":"Apag\u00f3n nacional (blackout) se registra en subestaci\u00f3n de San Pedro de Macor\u00eds"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><em>El evento sucedi\u00f3 a la 1:20 de la tarde de este martes<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"251\" height=\"251\" src=\"https:\/\/samantharadionline.com\/wp-content\/uploads\/2025\/11\/image.png\" alt=\"\" class=\"wp-image-21053\" style=\"width:48px;height:auto\" srcset=\"https:\/\/samantharadionline.com\/wp-content\/uploads\/2025\/11\/image.png 251w, https:\/\/samantharadionline.com\/wp-content\/uploads\/2025\/11\/image-150x150.png 150w\" sizes=\"auto, (max-width: 251px) 100vw, 251px\" \/><\/figure>\n\n\n\n<p><strong>Pablo Garc\u00eda<\/strong>, Santo Domingo\u00a0<\/p>\n\n\n\n<p>Un problema con la subestaci\u00f3n de la&nbsp;<strong>Empresa de Transmisi\u00f3n de Electricidad<\/strong>&nbsp;(ETED), ubicada en&nbsp;<strong>San Pedro de Macor\u00eds<\/strong>, provoc\u00f3 este martes una salida de todas las plantas de generaci\u00f3n el\u00e9ctrica del pa\u00eds, seg\u00fan confirm\u00f3 el presidente del&nbsp;<strong>Consejo Unificado de las Empresas<\/strong>&nbsp;<strong>Distribuidoras<\/strong>&nbsp;(<strong>CUED<\/strong>),&nbsp;<strong>Celso Marranzini<\/strong>.<\/p>\n\n\n\n<p>Marranzini explic\u00f3 que la situaci\u00f3n provoc\u00f3 que salieran en primer orden las plantas de la Compa\u00f1\u00eda de Electricidad de&nbsp;<strong>San Pedro de Macor\u00eds<\/strong>&nbsp;(Cespm) y luego las de&nbsp;<strong>AES Dominicana<\/strong>, lo que ocasion\u00f3 una salida en cadena del resto de las centrales del sistema, incluyendo Punta Catalina.<\/p>\n\n\n\n<p>\u00abEstamos subiendo el sistema lo m\u00e1s r\u00e1pido posible. Estamos entrando las&nbsp;<strong>hidroel\u00e9ctricas<\/strong>, y debemos tener el sistema repuesto en una&nbsp;<strong>dos o tres horas<\/strong>. La Empresa de Transmisi\u00f3n est\u00e1&nbsp;<strong>revisando<\/strong>&nbsp;exactamente qu\u00e9 fue lo que pas\u00f3 y se dar\u00e1 toda la informaci\u00f3n debida\u00bb, inform\u00f3.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfA qu\u00e9 hora se origin\u00f3?<\/h2>\n\n\n\n<p>De acuerdo con el gerente general del Organismo Coordinador (OC),&nbsp;<strong>Manuel L\u00f3pez San Pablo<\/strong>, el evento sucedi\u00f3 a la 1:20 de la tarde de este martes.<\/p>\n\n\n\n<p>\u00abHubo un evento en el sistema que estamos&nbsp;<strong>revisando<\/strong>&nbsp;todav\u00eda. Hay una&nbsp;<strong>falla<\/strong>&nbsp;que se produjo que estamos&nbsp;<strong>averiguando<\/strong>\u00ab, precis\u00f3 San Pablo.<\/p>\n\n\n\n<p>Dijo que el sistema se va a ir restableciendo y notific\u00f3 que ya hab\u00eda&nbsp;<strong>varias zonas<\/strong>&nbsp;con el&nbsp;<strong>servicio<\/strong>.<\/p>\n\n\n\n<p>\u00abVamos&nbsp;<strong>trabajando a la par&nbsp;<\/strong>con el sistema para que, a medida que vamos investigando (cu\u00e1l fue la&nbsp;<strong>falla<\/strong>), si esta persiste, no sigan pasando m\u00e1s cosas\u00bb, declar\u00f3. &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El evento sucedi\u00f3 a la 1:20 de la tarde de este martes Pablo Garc\u00eda, Santo<\/p>\n","protected":false},"author":1,"featured_media":21054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-21052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economica"],"_links":{"self":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/21052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/comments?post=21052"}],"version-history":[{"count":3,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/21052\/revisions"}],"predecessor-version":[{"id":21064,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/21052\/revisions\/21064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media\/21054"}],"wp:attachment":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media?parent=21052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/categories?post=21052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/tags?post=21052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}