{"id":19838,"date":"2025-09-26T19:57:45","date_gmt":"2025-09-26T23:57:45","guid":{"rendered":"https:\/\/samantharadionline.com\/?p=19838"},"modified":"2025-09-26T19:57:46","modified_gmt":"2025-09-26T23:57:46","slug":"dominicanos-tienen-6-de-las-20-camisetas-mas-vendidas-en-2025-de-grandes-ligas","status":"publish","type":"post","link":"https:\/\/samantharadionline.com\/index.php\/2025\/09\/26\/dominicanos-tienen-6-de-las-20-camisetas-mas-vendidas-en-2025-de-grandes-ligas\/","title":{"rendered":"Dominicanos tienen 6 de las 20 camisetas m\u00e1s vendidas en 2025 de Grandes Ligas"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><em>Shohei Otani es el que m\u00e1s camisetas vende de todo el negocio por tercer a\u00f1o seguido. Juan Soto es el dominicano con m\u00e1s camisetas vendidas<\/em><\/p>\n\n\n\n<p>R. L. D., <strong>Santo Domingo<\/strong>, <strong>R.D.<\/strong><\/p>\n\n\n\n<p>Seis\u00a0<strong>dominicanos\u00a0<\/strong>integran el listado de las 20\u00a0<strong>camisetas m\u00e1s vendidas\u00a0<\/strong>de la presente temporada de beisbol de las\u00a0<strong>Grandes Ligas.<\/strong><\/p>\n\n\n\n<p>Los dominicanos en la selecta lista son&nbsp;<strong>Juan Soto<\/strong>, de los Mets de Nueva York y en la posici\u00f3n 6 en sentido general;&nbsp;<strong>Rafael Devers<\/strong>,<strong>&nbsp;e<\/strong>n la 7, de los Gigantes de San Francisco y&nbsp;<strong>Fernando Tatis Jr.<\/strong>,en la n\u00famero 10, perteneciente a los Padres de San Diego.<\/p>\n\n\n\n<p>Los otros tres dominicanos en la lista son&nbsp;<strong>Elly de la Cruz<\/strong>, posici\u00f3n 14 y de los Rojos de Cincinnati;&nbsp;<strong>Vladimir Guerrero Jr.&nbsp;<\/strong>en la 15 de los Azulejos de Toronto y&nbsp;<strong>Manny Machado<\/strong>, en la 19, de los Padres de San Diego.<\/p>\n\n\n\n<p><strong>Shohei Otani es el que m\u00e1s camisetas vende<\/strong>&nbsp;de todo el negocio por tercer a\u00f1o seguido, seg\u00fan un comunicado de Grandes Ligas. Le siguen&nbsp;<strong>Aaron Judge, Freddie Freeman, Mookie Betts y Francisco Lindor.<\/strong><\/p>\n\n\n\n<p>El listado lo completan Bryce&nbsp;<strong>Harper&nbsp;<\/strong>(8), Jos\u00e9&nbsp;<strong>Altuve&nbsp;<\/strong>(9), Ronald&nbsp;<strong>Acu\u00f1a&nbsp;<\/strong>(11), Clayton&nbsp;<strong>Kershaw&nbsp;<\/strong>(12),&nbsp;<strong>Jarren Dur\u00e1n&nbsp;<\/strong>(13),&nbsp;<strong>Pete Crow-Armstrong<\/strong>&nbsp;(16), Pete&nbsp;<strong>Alonso&nbsp;<\/strong>(17), Paul&nbsp;<strong>Skenes&nbsp;<\/strong>(18) y Cal&nbsp;<strong>Raleigh&nbsp;<\/strong>(20).&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shohei Otani es el que m\u00e1s camisetas vende de todo el negocio por tercer a\u00f1o<\/p>\n","protected":false},"author":1,"featured_media":19839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-19838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/19838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/comments?post=19838"}],"version-history":[{"count":1,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/19838\/revisions"}],"predecessor-version":[{"id":19840,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/19838\/revisions\/19840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media\/19839"}],"wp:attachment":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media?parent=19838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/categories?post=19838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/tags?post=19838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}