{"id":13564,"date":"2025-03-10T13:06:50","date_gmt":"2025-03-10T12:06:50","guid":{"rendered":"https:\/\/samantharadionline.com\/?p=13564"},"modified":"2025-03-10T13:06:50","modified_gmt":"2025-03-10T12:06:50","slug":"prefiere-guante-de-oro-a-premio-mvp","status":"publish","type":"post","link":"https:\/\/samantharadionline.com\/index.php\/2025\/03\/10\/prefiere-guante-de-oro-a-premio-mvp\/","title":{"rendered":"Prefiere guante de oro a premio MVP"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">\u00a0<em>Soto ha expresado que su mayor anhelo es obtener un Guante de Oro, incluso por encima de un MVP<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/image_60_60\/uploads\/2024\/09\/17\/66ea20b960045.jpeg\" alt=\"Avatar del Moises Mej\u00eda\"\/><\/figure>\n\n\n\n<p><em>\u00a0<\/em>Moises Mej\u00eda, <strong>Santo Domingo, RD<\/strong><\/p>\n\n\n\n<p>A sus 26 a\u00f1os, Juan Soto ha alcanzado pr\u00e1cticamente todo en el b\u00e9isbol.<\/p>\n\n\n\n<p>Posee un anillo de Serie Mundial, ha ganado t\u00edtulo de bateo, ha sido seleccionado en cuatro ocasiones al Juego de Estrellas y ha obtenido cinco Bates de Plata. Y por si fuera poco, es due\u00f1o del contrato m\u00e1s grande en la historia del b\u00e9isbol: 15 a\u00f1os por 765 millones de d\u00f3lares con los Mets de Nueva York.&nbsp;<\/p>\n\n\n\n<p>Sin embargo, hay dos galardones que a\u00fan se le escapan: el premio al Jugador M\u00e1s Valioso (MVP) y el Guante de Oro.<\/p>\n\n\n\n<p>Sorprendentemente, Soto ha expresado que su mayor anhelo es obtener un Guante de Oro, incluso por encima de un MVP.<\/p>\n\n\n\n<p>\u201cPongo el Guante de Oro por encima del MVP porque ese premio abre muchas puertas y cierra muchas dudas. La gente puede pensar que no soy un buen defensor, pero he quedado segundo en la votaci\u00f3n del Guante de Oro tres veces, incluyendo la temporada pasada\u201d, dijo Soto durante una entrevista en Abriendo El Podcast, que producen los periodistas Vi\u00e1n Araujo y Ricardo Rodr\u00edguez.<\/p>\n\n\n\n<p>El dominicano revel\u00f3 que incluso actualmente centra sus entrenamientos m\u00e1s en la defensa que en la ofensiva.<\/p>\n\n\n\n<p>\u201cEstoy practicando m\u00e1s la defensa ahora mismo; es algo en lo que quiero seguir mejorando. Y me reto yo mismo a ser m\u00e1s exigente en esa faceta\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>Soto agradeci\u00f3 a los Yankees de Nueva York, ya que considera que fue el primer equipo que le mostr\u00f3 c\u00f3mo mejorar estad\u00edsticamente en la defensa, ense\u00f1\u00e1ndole las m\u00e9tricas necesarias para potenciar su rendimiento.<\/p>\n\n\n\n<p>\u201cLe agradezco mucho a Luis Rojas, porque cuando llegu\u00e9 a los Yankees, me dijeron: \u2018Mira, las m\u00e9tricas dicen esto, y t\u00fa tienes que hacer tal cosa para potenciar tu brazo\u2019. Me ayudaron con la potencia, la direcci\u00f3n, las rutas, y eso es algo por lo que siempre estar\u00e9 agradecido\u201d, coment\u00f3.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u201cJudge es el mejor\u201d<\/h3>\n\n\n\n<p>En otro sentido, Soto cerr\u00f3 recientemente una brecha que la prensa abri\u00f3 entre \u00e9l y Aaron Judge, capit\u00e1n de los Yankees de Nueva York.<\/p>\n\n\n\n<p>Tras dejar a los Mulos del Bronx para unirse a sus rivales de la Ciudad, los Mets, la prensa estadounidense ha motivado una supuesta ri\u00f1a entre Judge y Soto.<\/p>\n\n\n\n<p>La misma fue cortada de ra\u00edz por el dominicano. Soto describi\u00f3 a Judge como \u201cuna de las mejores personas\u201d que ha conocido dentro y fuera del b\u00e9isbol, destacando su liderazgo y calidad humana. Adem\u00e1s, dej\u00f3 claro que no hay nadie m\u00e1s indicado para llevar el t\u00edtulo de capit\u00e1n en los Yankees.<\/p>\n\n\n\n<p>\u201cAaron Judge es el mejor en todos los \u00e1mbitos. La forma en la que se maneja, c\u00f3mo trata a los compa\u00f1eros, es digna de admirar\u201d, afirm\u00f3 Soto.<\/p>\n\n\n\n<p>El estelar jardinero tambi\u00e9n valor\u00f3 que, a pesar de ser uno de los mejores jugadores del b\u00e9isbol, Judge nunca deja que su posici\u00f3n se le suba a la cabeza y mantiene una relaci\u00f3n de respeto con todos en el clubhouse.<\/p>\n\n\n\n<p>\u201cA todo el mundo lo hace sentir c\u00f3modo. Nadie se siente avergonzado con \u00e9l, porque les da un gran valor y respeto. Trata igual a un Sal\u00f3n de la Fama que a un novato reci\u00e9n subido desde las menores\u201d, a\u00f1adi\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Soto ha expresado que su mayor anhelo es obtener un Guante de Oro, incluso por<\/p>\n","protected":false},"author":1,"featured_media":13565,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-13564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/13564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/comments?post=13564"}],"version-history":[{"count":1,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/13564\/revisions"}],"predecessor-version":[{"id":13566,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/13564\/revisions\/13566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media\/13565"}],"wp:attachment":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media?parent=13564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/categories?post=13564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/tags?post=13564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}