{"id":11995,"date":"2025-01-23T01:26:03","date_gmt":"2025-01-23T00:26:03","guid":{"rendered":"https:\/\/samantharadionline.com\/?p=11995"},"modified":"2025-01-23T01:26:04","modified_gmt":"2025-01-23T00:26:04","slug":"juramentan-5-empresarios-como-miembros-de-comision-administrativa-para-reforma-policial","status":"publish","type":"post","link":"https:\/\/samantharadionline.com\/index.php\/2025\/01\/23\/juramentan-5-empresarios-como-miembros-de-comision-administrativa-para-reforma-policial\/","title":{"rendered":"Juramentan 5 empresarios como miembros de Comisi\u00f3n Administrativa para Reforma Policial"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><em>Los cinco empresarios (Celso Juan Marranzini, Pedro Brache, Elena Villeyas de Paliza, Marisol Bello y Ram\u00f3n Ortega) fueron designados por el mandatario \u00aben base a sus competencias profesionales y experiencias\u00bb morales<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/image_60_60\/uploads\/2023\/05\/16\/64638724a2bf3.jpeg\" alt=\"Avatar del Sauro Scalella\"\/><\/figure>\n\n\n\n<p><em>\u00a0<\/em>Sauro Scalella, <strong>Santo Domingo, RD<\/strong><\/p>\n\n\n\n<p>Este mi\u00e9rcoles,&nbsp;<strong>el presidente Luis Abinader<\/strong>&nbsp;ha juramentado a&nbsp;<strong>cinco empresarios<\/strong>&nbsp;como miembros del&nbsp;<strong>consejo consultivo para la transformaci\u00f3n administrativa y financiera de la Polic\u00eda Nacional,<\/strong>&nbsp;cuyo objetivo ser\u00e1 dise\u00f1ar e implementar un nuevo modelo de gesti\u00f3n de los recursos econ\u00f3micos para la&nbsp;<strong>Polic\u00eda Nacional.<\/strong><\/p>\n\n\n\n<p>Los cinco empresarios:&nbsp;<strong>Celso Juan Marranzini, Pedro Brache, Elena Villeyas de Paliza, Marisol Bello y Ram\u00f3n Ortega,&nbsp;<\/strong>fueron designados por el mandatario \u00aben base a sus competencias profesionales y experiencias\u00bb morales.<\/p>\n\n\n\n<p>Los nuevos miembros (tres hombres y dos mujeres) ejercer\u00e1n sus funciones de manera honor\u00edfica, indic\u00f3 el subconsultor jur\u00eddico del Poder Ejecutivo, Pedro Montilla.<\/p>\n\n\n\n<p>Montilla explic\u00f3 que los miembros trabajar\u00e1n bajo un consejo consultivo, cuyas competencias ser\u00e1n&nbsp;<strong>analizar y evaluar los diagn\u00f3sticos actuales relativos a la gesti\u00f3n administrativa y financiera de la Polic\u00eda Nacional<\/strong>.<\/p>\n\n\n\n<p>Adem\u00e1s, dise\u00f1ar\u00e1n un nuevo modelo de gesti\u00f3n administrativa y financiera para el cuerpo del orden, con el objetivo de \u00abfortalecer sus capacidades\u00bb financieras, apunt\u00f3 el subconsultor jur\u00eddico.<\/p>\n\n\n\n<p>Los miembros tambi\u00e9n tendr\u00e1n que proponer, para la revisi\u00f3n y aprobaci\u00f3n de la comisi\u00f3n ejecutiva, un&nbsp;<strong>plan de implementaci\u00f3n y ejecuci\u00f3n del nuevo modelo de gesti\u00f3n administrativa y financiera<\/strong>.<\/p>\n\n\n\n<p>Elena Villeyas de Paliza, que tambi\u00e9n ha formado parte de la Comisi\u00f3n de la Reforma Educativa Policial, explic\u00f3 que esta nueva comisi\u00f3n profundizar\u00e1 en el \u00e1rea administrativa y financiera, cuyo fin es asegurar que la gesti\u00f3n y el uso de los recursos que recibe la Polic\u00eda Nacional a trav\u00e9s de su presupuesto, as\u00ed como la gesti\u00f3n de los mismos, \u00ab<strong>se haga de forma eficiente y que el uso de los recursos sea el correcto y con mucha transparencia<\/strong>\u00ab.<\/p>\n\n\n\n<p>\u00abEs un paso importante porque ya profundiza en la parte presupuestaria y de c\u00f3mo se utilizan los recursos y c\u00f3mo se administra la polic\u00eda, tratando de lograr un uso eficiente y transparente de los mismos\u00bb, dijo Elena tras la juramentaci\u00f3n.<\/p>\n\n\n\n<p>El jefe del Estado no ofrecio un discurso sobre este tema y solo se limit\u00f3 a prestar juramento a los cinco miembros de la nueva comisi\u00f3n.<\/p>\n\n\n\n<p>\u201c<strong>Estoy seguro de que el pueblo dominicano se lo agradece y as\u00ed se lo agradecemos tambi\u00e9n, el gobierno y su presidente<\/strong>\u201d, dijo Abinader desde el Palacio Nacional, donde se desarroll\u00f3 el acto.<\/p>\n\n\n\n<p>La creaci\u00f3n del consejo, as\u00ed como los miembros que lo conforman, est\u00e1 contenida en los decretos 33-25 y 34-25, respectivamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los cinco empresarios (Celso Juan Marranzini, Pedro Brache, Elena Villeyas de Paliza, Marisol Bello y<\/p>\n","protected":false},"author":1,"featured_media":11996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-11995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/11995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/comments?post=11995"}],"version-history":[{"count":1,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/11995\/revisions"}],"predecessor-version":[{"id":11997,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/posts\/11995\/revisions\/11997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media\/11996"}],"wp:attachment":[{"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/media?parent=11995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/categories?post=11995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/samantharadionline.com\/index.php\/wp-json\/wp\/v2\/tags?post=11995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}